{"id":208,"date":"2023-06-06T22:40:53","date_gmt":"2023-06-06T22:40:53","guid":{"rendered":"https:\/\/urbanovamx.com\/blog\/?page_id=208"},"modified":"2024-04-02T15:58:00","modified_gmt":"2024-04-02T15:58:00","slug":"aviso-de-privacidad","status":"publish","type":"page","link":"https:\/\/urbanovamx.com\/blog\/aviso-de-privacidad\/","title":{"rendered":"AVISO DE PRIVACIDAD"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"208\" class=\"elementor elementor-208\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-12240e1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"12240e1\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3a90bce\" data-id=\"3a90bce\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4a1c310 elementor-widget elementor-widget-text-editor\" data-id=\"4a1c310\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong><u>RESPONSABLE DEL TRATAMIENTO DE DATOS PERSONALES:<\/u><\/strong><\/p>\n<p><strong><em>Nombre de la empresa:<\/em><\/strong> La persona moral denominada \u201cPARSS REALTOR CONSULTING GROUP\u201d SOCIEDAD DE RESPONSABILIDAD LIMITADA, la cual comercialmente es conocida como URBANOVA INMOBILIARIA.<\/p>\n<p><strong><em>Domicilio:<\/em><\/strong> Calle 3 # 144 x 14a y 16 Col. Mexico Norte de la ciudad y municipio de M\u00e9rida, Yucat\u00e1n, C\u00f3digo Postal 97128<\/p>\n<p><strong><em>Tel\u00e9fono:<\/em><\/strong> 9994.64.42.40<\/p>\n<p><strong><em>Correo Electr\u00f3nico:<\/em><\/strong> <a href=\"mailto:contacto@urbanovamx.com\">contacto@urbanovamx.com<\/a><\/p>\n<p>En cumplimiento de la legislaci\u00f3n aplicable en materia de protecci\u00f3n de datos personales en M\u00e9xico, se emite el presente Aviso de Privacidad para informarle sobre la forma en que recopilamos, utilizamos, almacenamos y protegemos los datos personales que usted proporciona al utilizar nuestro sitio web.<\/p>\n<p><strong><u>FINALIDADES DEL TRATAMIENTO DE DATOS PERSONALES:<\/u><\/strong><\/p>\n<p>Los datos personales que recopilamos tienen como finalidad:<\/p>\n<ul>\n<li>Confirmar y acreditar su identidad.<\/li>\n<li>Entender y atender sus necesidades de car\u00e1cter legal en materia <strong>inmobiliaria<\/strong>.<\/li>\n<li>Brindarle asesor\u00eda inmobiliaria en todo tipo de negociaciones y\/o conciliaciones.<\/li>\n<li>Cumplir con los requerimientos legales que le son aplicables.<\/li>\n<li>Verificar la informaci\u00f3n que nos proporciona.<\/li>\n<\/ul>\n<p><strong><u>DATOS PERSONALES RECOPILADOS:<\/u><\/strong><\/p>\n<p>Los datos personales que podemos recopilar incluyen, pero no se limitan a:<\/p>\n<ul>\n<li>Sus nombres, apellidos, sexo, nacionalidad, lugar y fecha de nacimiento, ocupaci\u00f3n y\/o actividad econ\u00f3mica y\/o giro y\/u objeto social, estado civil, domicilio, claves en el Registro Federal de Contribuyentes y\/o de la Clave \u00danica de Registro de Poblaci\u00f3n as\u00ed como folios de sus identificaciones oficiales.<br>\u2022 Su correo electr\u00f3nico y n\u00fameros telef\u00f3nicos, ya sean fijos o m\u00f3viles (celulares).<br>\u2022 Sus datos patrimoniales como cuentas bancarias, CLABES interbancarias, cr\u00e9ditos, hipotecas, embargos, fianzas, secuestros judiciales, bienes muebles e inmuebles, activos, pasivos, r\u00e9gimen fiscal, pagos de impuestos o contribuciones, domicilio y ubicaci\u00f3n de sus inmuebles, entre otros.<br>\u2022 Informaci\u00f3n sobre sus parientes, c\u00f3nyuge, concubino, herederos, legatarios y beneficiarios.<br>\u2022 Comprobantes oficiales que acrediten su identidad y la informaci\u00f3n que Usted declara.<\/li>\n<\/ul>\n<p><strong><u>FORMA DE RECOPILACI\u00d3N DE DATOS PERSONALES:<\/u><\/strong><\/p>\n<p>La recopilaci\u00f3n de sus datos personales se realiza a trav\u00e9s de formularios en l\u00ednea, cookies, mensajes SMS, registros del servidor, encuestas de nuestro call center y de nuestros consultores, y a trav\u00e9s de portales en l\u00ednea, as\u00ed como botones de llamada a la acci\u00f3n de redes sociales, as\u00ed como plataformas de mensajer\u00eda instant\u00e1neas. &nbsp;Al proporcionar sus datos personales, usted acepta y autoriza su uso de acuerdo con los t\u00e9rminos establecidos en este aviso de privacidad.<\/p>\n<p><strong><u>TRANSFERENCIA DE DATOS PERSONALES A TERCEROS:<\/u><\/strong><\/p>\n<p>Podemos transferir sus datos personales a terceros \u00fanicamente en los casos en que sea necesario para cumplir con proveedores de servicios externos, proveedores de IT y apps como CRM\u00b4s y socios comerciales. Nos comprometemos a garantizar que dichas transferencias cumplan con los requisitos legales aplicables y protejan adecuadamente su privacidad.<\/p>\n<p>&nbsp;En el caso de requerimientos o solicitudes que realicen las autoridades competentes tales como los registros p\u00fablicos, las autoridades tributarias, autoridades judiciales, Juzgados o Tribunales, Notarios P\u00fablicos, Ministerios P\u00fablicos as\u00ed como cualquier autoridad o tercero que acredite contar con inter\u00e9s jur\u00eddico, esta inmobiliaria se encuentra legalmente obligada a transferir esta informaci\u00f3n en los t\u00e9rminos y cumplimiento de la legislaci\u00f3n aplicable. Los datos personales no se transfieren a ning\u00fan tercero que no tenga inter\u00e9s jur\u00eddico o inter\u00e9s comercial como lo enunciado en el p\u00e1rrafo anterior.<\/p>\n<p><strong>DERECHOS ARCO:<\/strong><\/p>\n<p>Usted tiene derecho a acceder, rectificar, cancelar y oponerse al tratamiento de sus datos personales. Para ejercer estos derechos, o para solicitar la limitaci\u00f3n del uso o divulgaci\u00f3n de sus datos personales, puede comunicarse con nosotros a trav\u00e9s de los siguientes medios de contacto:<\/p>\n<p>&nbsp;No es posible limitar el uso o divulgaci\u00f3n de sus datos personales para el cumplimiento de obligaciones legales, en los que URBANOVA INMOBILIARIA proporciona a las autoridades competentes tales como registros p\u00fablicos, autoridades tributarias, autoridades judiciales, autoridades federales, autoridades estatales, archivos y colegios notariales, o a terceros que demuestren inter\u00e9s jur\u00eddico, todo ello en cumplimiento a la ley o a las normas aplicables a los abogados, Licenciados y Profesionales de Derecho, por lo que siempre y cuando no se infrinja por esta inmobiliaria alguna disposici\u00f3n legal, usted puede limitar el uso y divulgaci\u00f3n de su informaci\u00f3n personal a trav\u00e9s de los siguientes medios que hemos instrumentado:<\/p>\n<p>\u2022 Presentando su solicitud personalmente en nuestro domicilio (Calle 28 n\u00famero 373 por 9 y 39 de la colonia Emiliano Zapata norte de M\u00e9rida, Yucat\u00e1n, C.P. 97129) dirigida a la persona encargada de la privacidad en esta oficina.<br>\u2022 Enviando correo electr\u00f3nico a la siguiente direcci\u00f3n electr\u00f3nica:&nbsp;guzmandavid82@hotmail.com<br>\u2022 Llamando al n\u00famero telef\u00f3nico&nbsp;99994644240.<\/p>\n<p><strong><u>MEDIDAS DE SEGURIDAD:<\/u><\/strong><\/p>\n<p>Hemos implementado medidas de seguridad administrativas, t\u00e9cnicas y f\u00edsicas para proteger sus datos personales contra p\u00e9rdida, robo o acceso no autorizado. Nos comprometemos a mantener la confidencialidad y seguridad de sus datos personales y a utilizarlos \u00fanicamente para los fines establecidos en este aviso de privacidad.<\/p>\n<p><strong><u>PERIODO DE CONSERVACI\u00d3N DE DATOS:<\/u><\/strong><\/p>\n<p>Conservaremos sus datos personales durante el tiempo necesario para cumplir con las finalidades descritas anteriormente, a menos que usted solicite su cancelaci\u00f3n o hasta que sea legalmente requerido su mantenimiento.<\/p>\n<p><strong><u>\u00bfC\u00d3MO CONOCER LOS CAMBIOS AL PRESENTE AVISO DE PRIVACIDAD?<\/u><\/strong><\/p>\n<p>El presente aviso de privacidad puede sufrir modificaciones, cambios o actualizaciones por lo cual nos comprometemos a mantenerlo informado de tal situaci\u00f3n a trav\u00e9s de alguno de los siguientes medios:<\/p>\n<ul>\n<li>Nuestra p\u00e1gina de Internet&nbsp;<a href=\"http:\/\/www.urbanovamx.com.mx\">www.urbanovamx.com<\/a>.<\/li>\n<li>Notificaci\u00f3n a su correo electr\u00f3nico.<\/li>\n<li>En la primera comunicaci\u00f3n que tengamos con usted despu\u00e9s del cambio.<\/li>\n<\/ul>\n<p>Asimismo, ponemos a su entera disposici\u00f3n copias del presente aviso de privacidad en nuestro domicilio y en nuestra p\u00e1gina de Internet&nbsp;<a href=\"http:\/\/www.urbanovamx.com.mx\">www.urbanovamx.com<\/a>&nbsp;secci\u00f3n \u201cAviso de Privacidad\u201d.<\/p>\n<p><strong>Actualizaciones del aviso de privacidad \u00daltima revisi\u00f3n:&nbsp;JUNIO 2023.<\/strong><\/p>\n<p><\/p>\n<p style=\"text-align: center;\"><strong>RODRIGO JAIME PONCE AGUIAR<\/strong><\/p>\n<p style=\"text-align: center;\"><strong>ADMINISTRADOR UNICOC<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>RESPONSABLE DEL TRATAMIENTO DE DATOS PERSONALES: Nombre de la empresa: La persona moral denominada \u201cPARSS REALTOR CONSULTING GROUP\u201d SOCIEDAD DE RESPONSABILIDAD LIMITADA, la cual comercialmente es conocida como URBANOVA INMOBILIARIA&#8230;.<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-208","page","type-page","status-publish"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>AVISO DE PRIVACIDAD - Urbanova<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/urbanovamx.com\/blog\/aviso-de-privacidad\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"AVISO DE PRIVACIDAD - Urbanova\" \/>\n<meta property=\"og:description\" content=\"RESPONSABLE DEL TRATAMIENTO DE DATOS PERSONALES: Nombre de la empresa: La persona moral denominada \u201cPARSS REALTOR CONSULTING GROUP\u201d SOCIEDAD DE RESPONSABILIDAD LIMITADA, la cual comercialmente es conocida como URBANOVA INMOBILIARIA....\" \/>\n<meta property=\"og:url\" content=\"https:\/\/urbanovamx.com\/blog\/aviso-de-privacidad\/\" \/>\n<meta property=\"og:site_name\" content=\"Urbanova\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-02T15:58:00+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/urbanovamx.com\/blog\/aviso-de-privacidad\/\",\"url\":\"https:\/\/urbanovamx.com\/blog\/aviso-de-privacidad\/\",\"name\":\"AVISO DE PRIVACIDAD - Urbanova\",\"isPartOf\":{\"@id\":\"https:\/\/urbanovamx.com\/blog\/#website\"},\"datePublished\":\"2023-06-06T22:40:53+00:00\",\"dateModified\":\"2024-04-02T15:58:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/urbanovamx.com\/blog\/aviso-de-privacidad\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/urbanovamx.com\/blog\/aviso-de-privacidad\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/urbanovamx.com\/blog\/aviso-de-privacidad\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/urbanovamx.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AVISO DE PRIVACIDAD\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/urbanovamx.com\/blog\/#website\",\"url\":\"https:\/\/urbanovamx.com\/blog\/\",\"name\":\"Urbanova\",\"description\":\"Blog\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/urbanovamx.com\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"AVISO DE PRIVACIDAD - Urbanova","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/urbanovamx.com\/blog\/aviso-de-privacidad\/","og_locale":"es_ES","og_type":"article","og_title":"AVISO DE PRIVACIDAD - Urbanova","og_description":"RESPONSABLE DEL TRATAMIENTO DE DATOS PERSONALES: Nombre de la empresa: La persona moral denominada \u201cPARSS REALTOR CONSULTING GROUP\u201d SOCIEDAD DE RESPONSABILIDAD LIMITADA, la cual comercialmente es conocida como URBANOVA INMOBILIARIA....","og_url":"https:\/\/urbanovamx.com\/blog\/aviso-de-privacidad\/","og_site_name":"Urbanova","article_modified_time":"2024-04-02T15:58:00+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/urbanovamx.com\/blog\/aviso-de-privacidad\/","url":"https:\/\/urbanovamx.com\/blog\/aviso-de-privacidad\/","name":"AVISO DE PRIVACIDAD - Urbanova","isPartOf":{"@id":"https:\/\/urbanovamx.com\/blog\/#website"},"datePublished":"2023-06-06T22:40:53+00:00","dateModified":"2024-04-02T15:58:00+00:00","breadcrumb":{"@id":"https:\/\/urbanovamx.com\/blog\/aviso-de-privacidad\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/urbanovamx.com\/blog\/aviso-de-privacidad\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/urbanovamx.com\/blog\/aviso-de-privacidad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/urbanovamx.com\/blog\/"},{"@type":"ListItem","position":2,"name":"AVISO DE PRIVACIDAD"}]},{"@type":"WebSite","@id":"https:\/\/urbanovamx.com\/blog\/#website","url":"https:\/\/urbanovamx.com\/blog\/","name":"Urbanova","description":"Blog","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/urbanovamx.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/urbanovamx.com\/blog\/wp-json\/wp\/v2\/pages\/208","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/urbanovamx.com\/blog\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/urbanovamx.com\/blog\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/urbanovamx.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/urbanovamx.com\/blog\/wp-json\/wp\/v2\/comments?post=208"}],"version-history":[{"count":13,"href":"https:\/\/urbanovamx.com\/blog\/wp-json\/wp\/v2\/pages\/208\/revisions"}],"predecessor-version":[{"id":249,"href":"https:\/\/urbanovamx.com\/blog\/wp-json\/wp\/v2\/pages\/208\/revisions\/249"}],"wp:attachment":[{"href":"https:\/\/urbanovamx.com\/blog\/wp-json\/wp\/v2\/media?parent=208"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}